{"id":2502,"date":"2023-01-30T20:47:00","date_gmt":"2023-01-30T19:47:00","guid":{"rendered":"https:\/\/feuerwehr-oberriexingen.de\/content\/?post_type=einsatz&#038;p=2502"},"modified":"2023-01-31T06:54:36","modified_gmt":"2023-01-31T05:54:36","slug":"30-01-2023-h1-vu-unklare-lage","status":"publish","type":"einsatz","link":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/","title":{"rendered":"30.01.2023 &#8211; H1 VU unklare Lage"},"content":{"rendered":"\n<p>W\u00e4hrend des regul\u00e4ren \u00dcbungsdienst wurde die Feuerwehr Oberriexingen zu einem Verkehrsunfall alarmiert. Auf der Landstra\u00dfe zwischen Oberriexingen und Sersheim kam es zu einem Unfall mit zwei Pkw. Beim Eintreffen der Einsatzkr\u00e4fte waren die Helfer vor Ort und der Rettungsdienst bereits vor Ort. Alle Personen konnten bereits aus ihren Fahrzeugen befreit werden. Die Feuerwehr sicherte die Einsatzstelle ab, stellte den Brandschutz sicher und nahm Fl\u00fcssigkeiten auf. Anschlie\u00dfend wurde die Einsatzstelle f\u00fcr die Polizei ausgeleuchtet.\u00a0<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-2503\" src=\"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-300x225.jpg 300w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-768x576.jpg 768w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-1536x1152.jpg 1536w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-100x75.jpg 100w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-150x113.jpg 150w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-200x150.jpg 200w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-450x338.jpg 450w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-600x450.jpg 600w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980-900x675.jpg 900w, https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"author":2,"featured_media":2503,"template":"","meta":{"_cbd_carousel_blocks":"[]","einsatz_weight":1},"categories":[],"tags":[],"einsatzart":[9],"fahrzeug":[44,7],"exteinsatzmittel":[84,55,56,58],"alarmierungsart":[24],"evw_unit":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>30.01.2023 - H1 VU unklare Lage - Freiwillige Feuerwehr Oberriexingen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"30.01.2023 - H1 VU unklare Lage - Freiwillige Feuerwehr Oberriexingen\" \/>\n<meta property=\"og:description\" content=\"W\u00e4hrend des regul\u00e4ren \u00dcbungsdienst wurde die Feuerwehr Oberriexingen zu einem Verkehrsunfall alarmiert. Auf der Landstra\u00dfe zwischen Oberriexingen und Sersheim kam es zu einem Unfall mit zwei Pkw. Beim Eintreffen der Einsatzkr\u00e4fte waren die Helfer vor Ort und der Rettungsdienst bereits &hellip; 30.01.2023 &#8211; H1 VU unklare Lage Weiterlesen &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/\" \/>\n<meta property=\"og:site_name\" content=\"Freiwillige Feuerwehr Oberriexingen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ffwoberriexingen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T05:54:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/#website\",\"url\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/\",\"name\":\"Freiwillige Feuerwehr Oberriexingen\",\"description\":\"24h f\\u00fcr Sie im Einsatz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg\",\"contentUrl\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#webpage\",\"url\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/\",\"name\":\"30.01.2023 - H1 VU unklare Lage - Freiwillige Feuerwehr Oberriexingen\",\"isPartOf\":{\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#primaryimage\"},\"datePublished\":\"2023-01-30T19:47:00+00:00\",\"dateModified\":\"2023-01-31T05:54:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einsatzberichte\",\"item\":\"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"30.01.2023 &#8211; H1 VU unklare Lage\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"30.01.2023 - H1 VU unklare Lage - Freiwillige Feuerwehr Oberriexingen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/","og_locale":"de_DE","og_type":"article","og_title":"30.01.2023 - H1 VU unklare Lage - Freiwillige Feuerwehr Oberriexingen","og_description":"W\u00e4hrend des regul\u00e4ren \u00dcbungsdienst wurde die Feuerwehr Oberriexingen zu einem Verkehrsunfall alarmiert. Auf der Landstra\u00dfe zwischen Oberriexingen und Sersheim kam es zu einem Unfall mit zwei Pkw. Beim Eintreffen der Einsatzkr\u00e4fte waren die Helfer vor Ort und der Rettungsdienst bereits &hellip; 30.01.2023 &#8211; H1 VU unklare Lage Weiterlesen &raquo;","og_url":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/","og_site_name":"Freiwillige Feuerwehr Oberriexingen","article_publisher":"https:\/\/www.facebook.com\/ffwoberriexingen\/","article_modified_time":"2023-01-31T05:54:36+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg","type":"image\/jpeg"}],"twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/#website","url":"https:\/\/feuerwehr-oberriexingen.de\/content\/","name":"Freiwillige Feuerwehr Oberriexingen","description":"24h f\u00fcr Sie im Einsatz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/feuerwehr-oberriexingen.de\/content\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#primaryimage","inLanguage":"de","url":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg","contentUrl":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-content\/uploads\/2023\/01\/1675143091980.jpg","width":1600,"height":1200},{"@type":"WebPage","@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#webpage","url":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/","name":"30.01.2023 - H1 VU unklare Lage - Freiwillige Feuerwehr Oberriexingen","isPartOf":{"@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#primaryimage"},"datePublished":"2023-01-30T19:47:00+00:00","dateModified":"2023-01-31T05:54:36+00:00","breadcrumb":{"@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/30-01-2023-h1-vu-unklare-lage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/feuerwehr-oberriexingen.de\/content\/"},{"@type":"ListItem","position":2,"name":"Einsatzberichte","item":"https:\/\/feuerwehr-oberriexingen.de\/content\/einsaetze\/"},{"@type":"ListItem","position":3,"name":"30.01.2023 &#8211; H1 VU unklare Lage"}]}]}},"_links":{"self":[{"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/einsatz\/2502"}],"collection":[{"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/einsatz"}],"about":[{"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/types\/einsatz"}],"author":[{"embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/einsatz\/2502\/revisions"}],"predecessor-version":[{"id":2504,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/einsatz\/2502\/revisions\/2504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/media\/2503"}],"wp:attachment":[{"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/media?parent=2502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/categories?post=2502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/tags?post=2502"},{"taxonomy":"einsatzart","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/einsatzart?post=2502"},{"taxonomy":"fahrzeug","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/fahrzeug?post=2502"},{"taxonomy":"exteinsatzmittel","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/exteinsatzmittel?post=2502"},{"taxonomy":"alarmierungsart","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/alarmierungsart?post=2502"},{"taxonomy":"evw_unit","embeddable":true,"href":"https:\/\/feuerwehr-oberriexingen.de\/content\/wp-json\/wp\/v2\/evw_unit?post=2502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}